{"id":5816,"date":"2021-04-20T09:13:24","date_gmt":"2021-04-20T09:13:24","guid":{"rendered":"https:\/\/testaws02.nfactorial.eu\/establiments\/hotel-astoria-park\/"},"modified":"2021-04-20T09:32:14","modified_gmt":"2021-04-20T09:32:14","slug":"hotel-astoria-park","status":"publish","type":"avada_portfolio","link":"https:\/\/www.hotelslloret.com\/de\/establiments\/hotel-astoria-park\/","title":{"rendered":"Hotel Astoria Park"},"content":{"rendered":"<p>Unser kleines Hotel befindet sich im Handelszentrum von Lloret de Mar und ist ein Hotel, in dem Sie die Costa Brava mit der Freiheit, die das Leben im Zentrum bietet, entdecken und genie\u00dfen k\u00f6nnen.<br \/>\nAlle Dienstleistungen und Annehmlichkeiten, die f\u00fcr Sie entwickelt wurden, um zu entscheiden, wie Sie Ihren Urlaub w\u00fcnschen, werden wir Ihnen helfen, dies zu erm\u00f6glichen.<br \/>\nAnmerkung: K\u00fchlschrank im Zimmer und F\u00f6n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser kleines Hotel befindet sich im Handelszentrum von Lloret de Mar und ist ein Hotel, in dem Sie die Costa Brava mit der Freiheit, die das Leben im Zentrum bietet, entdecken und genie\u00dfen k\u00f6nnen.<br \/>\nAlle Dienstleistungen und Annehmlichkeiten, die f\u00fcr Sie entwickelt wurden, um zu entscheiden, wie Sie Ihren Urlaub w\u00fcnschen, werden wir Ihnen helfen, dies zu erm\u00f6glichen.<\/p>\n","protected":false},"author":2,"featured_media":5812,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[67],"portfolio_skills":[],"portfolio_tags":[70,71],"class_list":["post-5816","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-hotels-de","portfolio_tags-mit-der-familie-geniessen","portfolio_tags-spass-mit-freunden-haben"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/avada_portfolio\/5816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/comments?post=5816"}],"version-history":[{"count":3,"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/avada_portfolio\/5816\/revisions"}],"predecessor-version":[{"id":5827,"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/avada_portfolio\/5816\/revisions\/5827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/media\/5812"}],"wp:attachment":[{"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/media?parent=5816"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=5816"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=5816"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/www.hotelslloret.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=5816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}